{"id":16271,"date":"2020-06-10T18:52:10","date_gmt":"2020-06-10T16:52:10","guid":{"rendered":"https:\/\/bistrobadia.de\/balilah-warmer-kichererbsensalat\/"},"modified":"2024-01-19T05:53:19","modified_gmt":"2024-01-19T04:53:19","slug":"salada-de-gr%c3%a3o-de-bico-quente-balilah","status":"publish","type":"post","link":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/","title":{"rendered":"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados"},"content":{"rendered":"\n<p class=\"has-drop-cap\">H\u00e1 pratos sobre os quais eu adoraria escrever uma can\u00e7\u00e3o. Mas como infelizmente canto como um galo moribundo e n\u00e3o tenho sido muito bom a escrever can\u00e7\u00f5es, tenho o prazer de deixar esse prazer para v\u00f3s. Balilah \u00e9 um prato que merece definitivamente a sua pr\u00f3pria can\u00e7\u00e3o! A salada de gr\u00e3o de bico servida quente \u00e9 um must para um bom mezze.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-balilah-uma-grande-explosao-gustativa-com-apenas-alguns-ingredientes\">Balilah: Uma grande explos\u00e3o gustativa com apenas alguns ingredientes<\/h3>\n\n\n\n<p>Para muitos pratos da cozinha Levantine, s\u00f3 \u00e9 necess\u00e1rio um punhado de ingredientes, mas com a combina\u00e7\u00e3o certa obt\u00e9m-se um espect\u00e1culo de sabores absolutamente louco. Para balila, s\u00f3 \u00e9 preciso gr\u00e3o-de-bico, lim\u00e3o, salsa, cebolinha, pinh\u00f5es e uma pequena inunda\u00e7\u00e3o do melhor azeite. O lim\u00e3o \u00e9 utilizado na sua totalidade &#8211; mesmo a casca. Desta forma, \u00e9 poss\u00edvel trazer toda uma gama de sabores c\u00edtricos para a salada com apenas um ingrediente. O sumo de lim\u00e3o fornece a acidez necess\u00e1ria. A casca de lim\u00e3o, por outro lado, d\u00e1 a Balilah o aroma de uma planta\u00e7\u00e3o de lim\u00e3o e uma nota amarga realmente agrad\u00e1vel.<\/p>\n\n\n\n<p>Agora, antes de chamar \u00e0 salada &#8220;cinquenta tons de lim\u00e3o&#8221;, \u00e9 preciso saber que o gr\u00e3o-de-bico tamb\u00e9m \u00e9 usado duas vezes. Uma pequena parte do gr\u00e3o de bico, ainda quente, \u00e9 esmagada com alho, enquanto o resto \u00e9 adicionado inteiro. Isto d\u00e1 \u00e0 salada quente uma cremosidade absolutamente deliciosa. E quando depois se deparar com os pinh\u00f5es torrados, notar\u00e1 certamente como Balilah \u00e9 multifacetado. A prop\u00f3sito, o tempero de elei\u00e7\u00e3o aqui \u00e9 o cominho. O cominho mo\u00eddo n\u00e3o s\u00f3 proporciona um sabor agradavelmente salgado, como tamb\u00e9m torna o prato mais diger\u00edvel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-mezze-prato-inicial-e-prato-principal-em-um\">Mezze, prato inicial e prato principal em um<\/h3>\n\n\n\n<p>Balilah \u00e9 uma salada quente de gr\u00e3o de bico que pode servir em seguran\u00e7a como refei\u00e7\u00e3o principal. Posso realmente comer o meu recheio sem me fartar dele \ud83d\ude09 Tamb\u00e9m se pode encher a salada quente de gr\u00e3o de bico em tigelas pequenas e servi-la ao lado de <a rel=\"noreferrer noopener\" href=\"https:\/\/bistrobadia.de\/pt\/hummus\/\" target=\"_blank\">hummus<\/a>, <a rel=\"noreferrer noopener\" href=\"https:\/\/bistrobadia.de\/pt\/creme-de-beringela-baba-ghanoush\/\" target=\"_blank\">baba ghanoush<\/a>, <a rel=\"noreferrer noopener\" href=\"https:\/\/bistrobadia.de\/pt\/fa\u00e7a-o-seu-pr\u00f3prio-falafel\/\" target=\"_blank\">falafel<\/a> e afins.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-receita-para-balilah\">Receita para Balilah<\/h2>\n\n\n<div id=\"recipe\"><\/div><div id=\"wprm-recipe-container-28353\" class=\"wprm-recipe-container\" data-recipe-id=\"28353\" data-servings=\"2\"><div class=\"wprm-recipe wprm-recipe-template-bb2\"><div class=\"wprm-container-float-right\">\n    <div class=\"wprm-recipe-image wprm-block-image-normal\"><img decoding=\"async\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;border-width: 0px;border-style: solid;border-color: #666666;\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1024x683.jpg\" class=\"attachment-large size-large lazyload\" alt=\"Balilah warmer kichererbsensalat\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1024x683.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1536x1025.jpg 1536w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1920x1281.jpg 1920w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1170x780.jpg 1170w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-585x390.jpg 585w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-263x175.jpg 263w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/div>\n    \n<\/div>\n\n<div class=\"wprm-recipe-template-bb2-name-stars-container\">\n    <style>#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-full svg * { fill: #343434; }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-33 svg * { fill: url(#wprm-recipe-user-rating-0-33); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-50 svg * { fill: url(#wprm-recipe-user-rating-0-50); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-66 svg * { fill: url(#wprm-recipe-user-rating-0-66); }linearGradient#wprm-recipe-user-rating-0-33 stop { stop-color: #343434; }linearGradient#wprm-recipe-user-rating-0-50 stop { stop-color: #343434; }linearGradient#wprm-recipe-user-rating-0-66 stop { stop-color: #343434; }<\/style><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"0\" height=\"0\" style=\"display:block;width:0px;height:0px\"><defs><linearGradient id=\"wprm-recipe-user-rating-0-33\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-50\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-66\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><\/svg><div id=\"wprm-recipe-user-rating-0\" class=\"wprm-recipe-rating wprm-recipe-rating-recipe-28353 wprm-user-rating wprm-user-rating-not-voted wprm-user-rating-allowed\" data-recipe=\"28353\" data-average=\"0\" data-count=\"0\" data-total=\"0\" data-user=\"0\" data-decimals=\"2\"data-modal-uid=\"user-rating\"><span class=\"wprm-rating-star wprm-rating-star-1 wprm-rating-star-empty\" data-rating=\"1\" data-color=\"#343434\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 1 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#343434\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-2 wprm-rating-star-empty\" data-rating=\"2\" data-color=\"#343434\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 2 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#343434\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-3 wprm-rating-star-empty\" data-rating=\"3\" data-color=\"#343434\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 3 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#343434\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-4 wprm-rating-star-empty\" data-rating=\"4\" data-color=\"#343434\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 4 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#343434\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-5 wprm-rating-star-empty\" data-rating=\"5\" data-color=\"#343434\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 5 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#343434\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><\/div>\n<\/div>\n\n<div class=\"wprm-spacer\" style=\"height: 5px;\"><\/div>\n\n<span class=\"wprm-recipe-grow-container\"><a href=\"https:\/\/app.grow.me\" target=\"_blank\" rel=\"nofollow noreferrer\" style=\"color: #333333;background-color: #ffffff;border-color: #7ed321;border-radius: 5px;padding: 5px 5px;\" class=\"wprm-recipe-grow-not-saved wprm-recipe-grow wprm-recipe-link wprm-block-text-normal wprm-recipe-link-button wprm-color-accent\" data-recipe-id=\"28353\">Rezept speichern<\/a><a href=\"https:\/\/app.grow.me\" target=\"_blank\" rel=\"nofollow noreferrer\" style=\"color: #333333;background-color: #ffffff;border-color: #7ed321;border-radius: 5px;padding: 5px 5px;display: none;\" class=\"wprm-recipe-grow-saved wprm-recipe-grow wprm-recipe-link wprm-block-text-normal wprm-recipe-link-button wprm-color-accent\" data-recipe-id=\"28353\">Gespeichert!<\/a><\/span>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-recipe-meta-container wprm-recipe-times-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-prep-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-bold wprm-recipe-time-label wprm-recipe-prep-time-label\">Prep Time <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-prep_time wprm-recipe-prep_time-minutes\">10<span class=\"sr-only screen-reader-text wprm-screen-reader-text\"> minutes<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-prep_time-unit wprm-recipe-prep_timeunit-minutes\" aria-hidden=\"true\">Min.<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-cook-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-bold wprm-recipe-time-label wprm-recipe-cook-time-label\">Cook Time <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-cook_time wprm-recipe-cook_time-minutes\">15<span class=\"sr-only screen-reader-text wprm-screen-reader-text\"> minutes<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-cook_time-unit wprm-recipe-cook_timeunit-minutes\" aria-hidden=\"true\">Min.<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-total-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-bold wprm-recipe-time-label wprm-recipe-total-time-label\">Total Time <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-total_time wprm-recipe-total_time-minutes\">25<span class=\"sr-only screen-reader-text wprm-screen-reader-text\"> minutes<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-total_time-unit wprm-recipe-total_timeunit-minutes\" aria-hidden=\"true\">Min.<\/span><\/span><\/div><\/div>\n<div class=\"wprm-recipe-meta-container wprm-recipe-custom-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-servings-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-bold wprm-recipe-servings-label\">Servings <\/span><span class=\"wprm-recipe-servings-with-unit\"><span class=\"wprm-recipe-servings wprm-recipe-details wprm-recipe-servings-28353 wprm-recipe-servings-adjustable-tooltip wprm-block-text-normal\" data-recipe=\"28353\" aria-label=\"Adjust recipe servings\">2<\/span> <span class=\"wprm-recipe-servings-unit wprm-recipe-details-unit wprm-block-text-normal\">x refei\u00e7\u00e3o principal<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-nutrition-container wprm-recipe-calories-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-bold wprm-recipe-nutrition-label wprm-recipe-calories-label\">Calories <\/span><span class=\"wprm-recipe-details wprm-recipe-nutrition wprm-recipe-calories wprm-block-text-normal\">755<\/span><\/div><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n<div id=\"recipe-28353-ingredients\" class=\"wprm-recipe-ingredients-container wprm-recipe-ingredients-no-images wprm-recipe-28353-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"28353\" data-servings=\"2\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">500<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">g<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">Gr\u00e3o-de-bico cozido<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">30<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">g<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">Salsa de folha achatada<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">30<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">g<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">Pinh\u00f5es<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">Lim\u00e3o\u00a0<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">Org\u00e2nico<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">Cebola de primavera<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"5\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">\u00a0Dente de alho<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"6\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">TSP<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">\u00a0Cumin\u00a0<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">terreno<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"7\"><span class=\"wprm-recipe-ingredient-amount\">100<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">\u00a0<a href=\"https:\/\/amzn.to\/36Vq6LL\" target=\"_blank\" rel=\"nofollow\">Azeite de oliva<\/a><\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"8\"><span class=\"wprm-recipe-ingredient-name\">Sal, pimenta<\/span><\/li><\/ul><\/div><\/div>\n\n<script async src=\"https:\/\/cdn.foodinfluencersunited.com\/r2b.js\"><\/script>\n\n<div id=\"recipe-28353-instructions\" class=\"wprm-recipe-instructions-container wprm-recipe-28353-instructions-container wprm-block-text-normal\" data-recipe=\"28353\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Zubereitung<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-28353-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Colocar o gr\u00e3o de bico cozido numa panela com \u00e1gua (ou o l\u00edquido da lata) e ferver em lume brando durante cerca de 10 minutos.<\/span><\/div><\/li><li id=\"wprm-recipe-28353-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Entretanto, corta-se a salsa e cortam-se as cebolinhas em an\u00e9is.<\/span><\/div><\/li><li id=\"wprm-recipe-28353-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Descascar o alho e esmaga-lo finamente num almofariz com um pouco de sal.<\/span><\/div><\/li><li id=\"wprm-recipe-28353-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Lavar e espremer o lim\u00e3o e cortar finamente uma das metades de lim\u00e3o espremido.<\/span><\/div><\/li><li id=\"wprm-recipe-28353-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Torrar os pinh\u00f5es durante aproximadamente 3 &#8211; 5 minutos sem gordura numa frigideira em lume forte, mexendo constantemente, at\u00e9 ficarem castanhos dourados e deixados de lado para arrefecer.<\/span><\/div><\/li><li id=\"wprm-recipe-28353-step-0-5\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Colocar o alho esmagado numa grande saladeira. Adicionar um quarto do gr\u00e3o de bico e mosto.<\/span><\/div><\/li><li id=\"wprm-recipe-28353-step-0-6\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Adicionar o resto do gr\u00e3o de bico com todos os ingredientes e misturar bem. Tempere com cominho, sal e pimenta.<\/span><\/div><\/li><li id=\"wprm-recipe-28353-step-0-7\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\"><span style=\"display: block;\">Servir balilah quente com p\u00e3o pita.<\/span><\/div><\/li><\/ul><\/div><\/div>\n\n<div id=\"recipe-28353-notes\" class=\"wprm-recipe-notes-container wprm-block-text-normal\"><h3 class=\"wprm-recipe-header wprm-recipe-notes-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Notes<\/h3><div class=\"wprm-recipe-notes\"><div class=\"wprm-recipe-notes-container wprm-block-text-normal\">\n<div class=\"wprm-recipe-notes\">\n<div class=\"wprm-recipe-notes-container wprm-block-text-normal\">\n<div class=\"wprm-recipe-notes\">\n<div class=\"wprm-recipe-notes-container wprm-block-text-normal\">\n<div class=\"wprm-recipe-notes\">A receita cont\u00e9m o link de afilia\u00e7\u00e3o.\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n<div id=\"recipe-28353-nutrition\" class=\"wprm-nutrition-label-shortcode-container\"><h3 class=\"wprm-recipe-header wprm-recipe-nutrition-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">N\u00e4hrwerte<\/h3><div class=\"wprm-nutrition-label-container wprm-nutrition-label-container-simple wprm-block-text-normal\" style=\"text-align: left;\"><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-calories\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Calories: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">755<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">kcal<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-carbohydrates\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Hidratos de carbono: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">43<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-protein\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Prote\u00ednas: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">16<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-fat\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Gordura: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">61<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-saturated_fat\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Gordura saturada: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">8<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-polyunsaturated_fat\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Gordura polinsaturada: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">12<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-monounsaturated_fat\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Gordura monoinsaturada: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">37<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-sodium\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">S\u00f3dio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">710<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-potassium\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Pot\u00e1ssio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">665<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-fiber\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Fiber: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">14<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-sugar\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">A\u00e7\u00facar: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">2<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">g<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-vitamin_a\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Vitamina A: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">1450<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">IU<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-vitamin_c\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Vitamina C: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">52<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-calcium\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">C\u00e1lcio: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">146<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><span style=\"color: #777777\"> | <\/span><span class=\"wprm-nutrition-label-text-nutrition-container wprm-nutrition-label-text-nutrition-container-iron\"><span class=\"wprm-nutrition-label-text-nutrition-label  wprm-block-text-normal\" style=\"color: #777777\">Ferro: <\/span><span class=\"wprm-nutrition-label-text-nutrition-value\" style=\"color: #333333\">6<\/span><span class=\"wprm-nutrition-label-text-nutrition-unit\" style=\"color: #333333\">mg<\/span><\/span><\/div><\/div><\/div><\/div>\n\n\n<p>Aprenda tudo o que precisa de saber sobre gr\u00e3o-de-bico no meu <a href=\"https:\/\/bistrobadia.de\/pt\/guia-do-gr\u00e3o-de-bico\/\" target=\"_blank\" rel=\"noreferrer noopener\">guia<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 pratos sobre os quais eu adoraria escrever uma can\u00e7\u00e3o&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":16272,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[4626,4628,4629,4630,4631,4632],"tags":[],"class_list":["post-16271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-klassiker-rezepte","category-mezze-rezepte","category-salat-rezepte","category-rapidamente-conjurado","category-vegan-rezepte","category-vegetarisch-rezepte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados<\/title>\n<meta name=\"description\" content=\"Balilah \u00e9 uma deliciosa salada de gr\u00e3o de bico servida quente com gr\u00e3o de bico acabado de assar. Um cl\u00e1ssico da cozinha Levantina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados\" \/>\n<meta property=\"og:description\" content=\"Balilah \u00e9 uma deliciosa salada de gr\u00e3o de bico servida quente com gr\u00e3o de bico acabado de assar. Um cl\u00e1ssico da cozinha Levantina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/\" \/>\n<meta property=\"og:site_name\" content=\"Bistro Badia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bistrobadia\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-10T16:52:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T04:53:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafik Halabi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafik Halabi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/\"},\"author\":{\"name\":\"Rafik Halabi\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#\\\/schema\\\/person\\\/fa7e5cf95714a3582b7a4e1bc990e0ad\"},\"headline\":\"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados\",\"datePublished\":\"2020-06-10T16:52:10+00:00\",\"dateModified\":\"2024-01-19T04:53:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/\"},\"wordCount\":580,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Balilah-warmer-kichererbsensalat.jpg\",\"articleSection\":[\"Cl\u00e1ssico\",\"Mezze\",\"Salada\",\"rapidamente conjurado\",\"Vegan\",\"Vegetariano\"],\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/\",\"name\":\"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Balilah-warmer-kichererbsensalat.jpg\",\"datePublished\":\"2020-06-10T16:52:10+00:00\",\"dateModified\":\"2024-01-19T04:53:19+00:00\",\"description\":\"Balilah \u00e9 uma deliciosa salada de gr\u00e3o de bico servida quente com gr\u00e3o de bico acabado de assar. Um cl\u00e1ssico da cozinha Levantina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/#breadcrumb\"},\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Balilah-warmer-kichererbsensalat.jpg\",\"contentUrl\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Balilah-warmer-kichererbsensalat.jpg\",\"width\":2048,\"height\":1366},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/salada-de-gr%c3%a3o-de-bico-quente-balilah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salada\",\"item\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/categoria\\\/salat-rezepte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/\",\"name\":\"Bistro Badia\",\"description\":\"Rezepte aus dem Libanon und der Levante\",\"publisher\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#organization\",\"name\":\"Bistro Badia\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/kleines-logo-gr\u00fcn.jpg\",\"contentUrl\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/kleines-logo-gr\u00fcn.jpg\",\"width\":2048,\"height\":1448,\"caption\":\"Bistro Badia\"},\"image\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bistrobadia\",\"https:\\\/\\\/www.instagram.com\\\/bistrobadia.de\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/bistrobadia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#\\\/schema\\\/person\\\/fa7e5cf95714a3582b7a4e1bc990e0ad\",\"name\":\"Rafik Halabi\",\"description\":\"Hey! Willkommen auf Bistro Badia! Ich bin Rafik und ich freue mich sehr, dass Du hier bist.\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/author\\\/rafik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados","description":"Balilah \u00e9 uma deliciosa salada de gr\u00e3o de bico servida quente com gr\u00e3o de bico acabado de assar. Um cl\u00e1ssico da cozinha Levantina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/","og_locale":"pt_PT","og_type":"article","og_title":"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados","og_description":"Balilah \u00e9 uma deliciosa salada de gr\u00e3o de bico servida quente com gr\u00e3o de bico acabado de assar. Um cl\u00e1ssico da cozinha Levantina.","og_url":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/","og_site_name":"Bistro Badia","article_publisher":"https:\/\/www.facebook.com\/bistrobadia","article_published_time":"2020-06-10T16:52:10+00:00","article_modified_time":"2024-01-19T04:53:19+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat.jpg","type":"image\/jpeg"}],"author":"Rafik Halabi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rafik Halabi","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/#article","isPartOf":{"@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/"},"author":{"name":"Rafik Halabi","@id":"https:\/\/bistrobadia.de\/pt\/#\/schema\/person\/fa7e5cf95714a3582b7a4e1bc990e0ad"},"headline":"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados","datePublished":"2020-06-10T16:52:10+00:00","dateModified":"2024-01-19T04:53:19+00:00","mainEntityOfPage":{"@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/"},"wordCount":580,"commentCount":0,"publisher":{"@id":"https:\/\/bistrobadia.de\/pt\/#organization"},"image":{"@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/#primaryimage"},"thumbnailUrl":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat.jpg","articleSection":["Cl\u00e1ssico","Mezze","Salada","rapidamente conjurado","Vegan","Vegetariano"],"inLanguage":"pt","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/","url":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/","name":"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados","isPartOf":{"@id":"https:\/\/bistrobadia.de\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/#primaryimage"},"image":{"@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/#primaryimage"},"thumbnailUrl":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat.jpg","datePublished":"2020-06-10T16:52:10+00:00","dateModified":"2024-01-19T04:53:19+00:00","description":"Balilah \u00e9 uma deliciosa salada de gr\u00e3o de bico servida quente com gr\u00e3o de bico acabado de assar. Um cl\u00e1ssico da cozinha Levantina.","breadcrumb":{"@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/#breadcrumb"},"inLanguage":"pt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/"]}]},{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/#primaryimage","url":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat.jpg","contentUrl":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat.jpg","width":2048,"height":1366},{"@type":"BreadcrumbList","@id":"https:\/\/bistrobadia.de\/pt\/salada-de-gr%c3%a3o-de-bico-quente-balilah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/bistrobadia.de\/pt\/"},{"@type":"ListItem","position":2,"name":"Salada","item":"https:\/\/bistrobadia.de\/pt\/categoria\/salat-rezepte\/"},{"@type":"ListItem","position":3,"name":"Balilah: Salada quente de gr\u00e3o de bico com pinh\u00f5es assados"}]},{"@type":"WebSite","@id":"https:\/\/bistrobadia.de\/pt\/#website","url":"https:\/\/bistrobadia.de\/pt\/","name":"Bistro Badia","description":"Rezepte aus dem Libanon und der Levante","publisher":{"@id":"https:\/\/bistrobadia.de\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bistrobadia.de\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt"},{"@type":"Organization","@id":"https:\/\/bistrobadia.de\/pt\/#organization","name":"Bistro Badia","url":"https:\/\/bistrobadia.de\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/bistrobadia.de\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/kleines-logo-gr\u00fcn.jpg","contentUrl":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/kleines-logo-gr\u00fcn.jpg","width":2048,"height":1448,"caption":"Bistro Badia"},"image":{"@id":"https:\/\/bistrobadia.de\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bistrobadia","https:\/\/www.instagram.com\/bistrobadia.de\/","https:\/\/www.pinterest.de\/bistrobadia\/"]},{"@type":"Person","@id":"https:\/\/bistrobadia.de\/pt\/#\/schema\/person\/fa7e5cf95714a3582b7a4e1bc990e0ad","name":"Rafik Halabi","description":"Hey! Willkommen auf Bistro Badia! Ich bin Rafik und ich freue mich sehr, dass Du hier bist.","url":"https:\/\/bistrobadia.de\/pt\/author\/rafik\/"}]}},"taxonomy_info":{"category":[{"value":4626,"label":"Cl\u00e1ssico"},{"value":4628,"label":"Mezze"},{"value":4629,"label":"Salada"},{"value":4630,"label":"rapidamente conjurado"},{"value":4631,"label":"Vegan"},{"value":4632,"label":"Vegetariano"}]},"featured_image_src_large":["https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1024x683.jpg",1024,683,true],"author_info":{"display_name":"Rafik Halabi","author_link":"https:\/\/bistrobadia.de\/pt\/author\/rafik\/"},"comment_info":0,"category_info":[{"term_id":4626,"name":"Cl\u00e1ssico","slug":"klassiker-rezepte","term_group":0,"term_taxonomy_id":4626,"taxonomy":"category","description":"Estes s\u00e3o os cl\u00e1ssicos absolutos da cozinha Levantina. Descubra receitas como falafel, shawarma, fasolia e e! Aut\u00eantico e simplesmente delicioso! D\u00ea uma vista de olhos e descubra a cozinha do Levante.","parent":0,"count":127,"filter":"raw","term_order":"10","cat_ID":4626,"category_count":127,"category_description":"Estes s\u00e3o os cl\u00e1ssicos absolutos da cozinha Levantina. Descubra receitas como falafel, shawarma, fasolia e e! Aut\u00eantico e simplesmente delicioso! D\u00ea uma vista de olhos e descubra a cozinha do Levante.","cat_name":"Cl\u00e1ssico","category_nicename":"klassiker-rezepte","category_parent":0},{"term_id":4628,"name":"Mezze","slug":"mezze-rezepte","term_group":0,"term_taxonomy_id":4628,"taxonomy":"category","description":"Mezze \u00e9 uma pe\u00e7a central da cultura alimentar Levantine. Tal como as tapas, trata-se de muitas pequenas coisas em cima da mesa para partilhar. Um mezze realmente bom inclui sempre p\u00e3o pita fresco, hummus, taboul\u00e9 e legumes fritos. Mas h\u00e1 tanta coisa que se pode tentar. D\u00ea uma vista de olhos e crie a sua pr\u00f3pria mesa de mezze.","parent":0,"count":68,"filter":"raw","term_order":"12","cat_ID":4628,"category_count":68,"category_description":"Mezze \u00e9 uma pe\u00e7a central da cultura alimentar Levantine. Tal como as tapas, trata-se de muitas pequenas coisas em cima da mesa para partilhar. Um mezze realmente bom inclui sempre p\u00e3o pita fresco, hummus, taboul\u00e9 e legumes fritos. Mas h\u00e1 tanta coisa que se pode tentar. D\u00ea uma vista de olhos e crie a sua pr\u00f3pria mesa de mezze.","cat_name":"Mezze","category_nicename":"mezze-rezepte","category_parent":0},{"term_id":4629,"name":"Salada","slug":"salat-rezepte","term_group":0,"term_taxonomy_id":4629,"taxonomy":"category","description":"As saladas correm sempre bem! Seja como prato secund\u00e1rio ou como refei\u00e7\u00e3o principal propriamente dita, depende inteiramente de si. Em qualquer caso, encontrar\u00e1 aqui uma grande selec\u00e7\u00e3o de diferentes receitas de salada. Divirta-se a navegar!","parent":0,"count":35,"filter":"raw","term_order":"13","cat_ID":4629,"category_count":35,"category_description":"As saladas correm sempre bem! Seja como prato secund\u00e1rio ou como refei\u00e7\u00e3o principal propriamente dita, depende inteiramente de si. Em qualquer caso, encontrar\u00e1 aqui uma grande selec\u00e7\u00e3o de diferentes receitas de salada. Divirta-se a navegar!","cat_name":"Salada","category_nicename":"salat-rezepte","category_parent":0},{"term_id":4630,"name":"rapidamente conjurado","slug":"rapidamente-conjurado","term_group":0,"term_taxonomy_id":4630,"taxonomy":"category","description":"Sob a categoria \"rapidamente conjurado\" encontrar\u00e1 numerosas receitas que s\u00e3o particularmente r\u00e1pidas de preparar. A sua refei\u00e7\u00e3o estar\u00e1 sobre a mesa dentro de 15 a 45 minutos! Perfeito para um almo\u00e7o r\u00e1pido ou para uma cozinha depois do trabalho.","parent":0,"count":135,"filter":"raw","term_order":"14","cat_ID":4630,"category_count":135,"category_description":"Sob a categoria \"rapidamente conjurado\" encontrar\u00e1 numerosas receitas que s\u00e3o particularmente r\u00e1pidas de preparar. A sua refei\u00e7\u00e3o estar\u00e1 sobre a mesa dentro de 15 a 45 minutos! Perfeito para um almo\u00e7o r\u00e1pido ou para uma cozinha depois do trabalho.","cat_name":"rapidamente conjurado","category_nicename":"rapidamente-conjurado","category_parent":0},{"term_id":4631,"name":"Vegan","slug":"vegan-rezepte","term_group":0,"term_taxonomy_id":4631,"taxonomy":"category","description":"Gosta que a sua comida esteja completamente livre de produtos animais? Ent\u00e3o veio ao lugar certo! As receitas nesta categoria s\u00e3o todas naturalmente veganas ou podem ser rapidamente tornadas veganas com uma alternativa baseada em plantas.","parent":0,"count":104,"filter":"raw","term_order":"16","cat_ID":4631,"category_count":104,"category_description":"Gosta que a sua comida esteja completamente livre de produtos animais? Ent\u00e3o veio ao lugar certo! As receitas nesta categoria s\u00e3o todas naturalmente veganas ou podem ser rapidamente tornadas veganas com uma alternativa baseada em plantas.","cat_name":"Vegan","category_nicename":"vegan-rezepte","category_parent":0},{"term_id":4632,"name":"Vegetariano","slug":"vegetarisch-rezepte","term_group":0,"term_taxonomy_id":4632,"taxonomy":"category","description":"H\u00e1 tantos pratos vegetarianos deliciosos do Levante. O bom gosto n\u00e3o precisa realmente de produtos animais. D\u00ea uma vista de olhos e deixe que as receitas vegetarianas o inspirem.","parent":0,"count":184,"filter":"raw","term_order":"17","cat_ID":4632,"category_count":184,"category_description":"H\u00e1 tantos pratos vegetarianos deliciosos do Levante. O bom gosto n\u00e3o precisa realmente de produtos animais. D\u00ea uma vista de olhos e deixe que as receitas vegetarianas o inspirem.","cat_name":"Vegetariano","category_nicename":"vegetarisch-rezepte","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/posts\/16271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/comments?post=16271"}],"version-history":[{"count":0,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/posts\/16271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/media\/16272"}],"wp:attachment":[{"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/media?parent=16271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/categories?post=16271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/tags?post=16271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}