{"id":16520,"date":"2020-05-27T14:30:56","date_gmt":"2020-05-27T12:30:56","guid":{"rendered":"https:\/\/bistrobadia.de\/kichererbsen-guide\/"},"modified":"2024-01-25T12:54:53","modified_gmt":"2024-01-25T11:54:53","slug":"guia-do-gr%c3%a3o-de-bico","status":"publish","type":"post","link":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/","title":{"rendered":"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber sobre a ervilha pequena"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Imagine se n\u00e3o houvesse gr\u00e3o de bico&#8230; Ent\u00e3o n\u00e3o havia <a href=\"https:\/\/bistrobadia.de\/pt\/fa\u00e7a-o-seu-pr\u00f3prio-falafel\/\">falafel<\/a>, nem <a href=\"https:\/\/bistrobadia.de\/pt\/hummus\/\" target=\"_blank\" rel=\"noreferrer noopener\">hummus<\/a>, nem <a href=\"https:\/\/bistrobadia.de\/pt\/salada-de-gr\u00e3o-de-bico-com-molho-de-zaatar\/\" target=\"_blank\" rel=\"noreferrer noopener\">salada de gr\u00e3o de bico<\/a>&#8230; OMG! Isso n\u00e3o \u00e9 poss\u00edvel e, felizmente, tamb\u00e9m n\u00e3o temos de o imaginar. N\u00e3o \u00e9 por nada que o gr\u00e3o de bico \u00e9 um alimento b\u00e1sico em muitos pa\u00edses. E, entretanto, est\u00e3o tamb\u00e9m a aparecer cada vez com mais frequ\u00eancia nas nossas placas. Descubra de onde vem, qu\u00e3o saud\u00e1vel \u00e9 e o que precisa de ter em mente quando o preparar aqui no guia do gr\u00e3o de bico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-origem-do-grao-de-bico\">Origem do gr\u00e3o de bico<\/h3>\n\n\n\n<p>O gr\u00e3o de bico j\u00e1 era cultivado h\u00e1 cerca de <strong>8000 anos<\/strong> no Pr\u00f3ximo Oriente, <strong>Turquia<\/strong>, e \u00e9 uma das <strong>plantas cultivadas mais antigas<\/strong> do mundo. A partir da\u00ed veio para a Europa na Idade M\u00e9dia via \u00cdndia e Norte de \u00c1frica. No M\u00e9xico e na \u00cdndia e em muitos outros pa\u00edses do mundo, o gr\u00e3o-de-bico \u00e9 um <strong>alimento b\u00e1sico<\/strong>. O gr\u00e3o-de-bico \u00e9 barato, super nutritivo e vers\u00e1til. A \u00cdndia \u00e9 o maior pa\u00eds produtor de gr\u00e3o de bico, mas a planta \u00e9 tamb\u00e9m amplamente cultivada e exportada no Norte de \u00c1frica, Turquia, Austr\u00e1lia e Espanha.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"681\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-1024x681.jpg\" alt=\"Kichererbsen gr\u00fcn\" class=\"wp-image-6471 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-1024x681.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-768x511.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-1536x1022.jpg 1536w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-2048x1363.jpg 2048w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-1920x1278.jpg 1920w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-1170x779.jpg 1170w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-585x389.jpg 585w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-gr\u00fcn-263x175.jpg 263w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/681;\" \/><figcaption class=\"wp-element-caption\">H\u00e1 uma pequena vagem para cada gr\u00e3o de bico.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-um-fruto-com-casca\">Um fruto com casca<\/h3>\n\n\n\n<p>O gr\u00e3o de bico pertence \u00e0 fam\u00edlia das <strong>leguminosas<\/strong>. Assim, feij\u00e3o, lentilhas e soja s\u00e3o os seus irm\u00e3os. Deve o seu <strong>nome \u00e0<\/strong> palavra latina <strong>&#8220;cicer <\/strong>&#8221; [alem\u00e3o: ervilha]. Existem diferentes variedades, mas para a cozinha, duas variedades s\u00e3o particularmente populares. Aqui na Europa, o chamado <strong>tipo Kabuli<\/strong> \u00e9 o mais comum. As ervilhas s\u00e3o grandes, de cor amarelo-bege, t\u00eam um sabor ligeiramente a nozes e crescem particularmente bem na regi\u00e3o mediterr\u00e2nica. O tipo Desi vem da \u00cdndia e \u00e9 menor e mais escuro do que o gr\u00e3o de bico da Europa.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" autoplay controls src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/1034362667-hd.mov\"><\/video><figcaption class=\"wp-element-caption\">Tal como as ervilhas verdes, o gr\u00e3o-de-bico est\u00e1 numa vagem.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-o-que-e-que-esta-la-dentro\">O que \u00e9 que est\u00e1 l\u00e1 dentro?<\/h3>\n\n\n\n<p>Uma coisa \u00e9 certa: quando o gr\u00e3o de bico aterra no seu prato, est\u00e1 a fazer algo de bom para si e para o seu corpo. S\u00e3o uma <strong>alternativa<\/strong> ideal <strong>\u00e0s prote\u00ednas animais<\/strong>, porque est\u00e3o cheias de <strong>prote\u00ednas<\/strong>. 100 g de gr\u00e3o de bico cont\u00eam cerca de 19 gramas de prote\u00edna, o que \u00e9 uma boa quantidade de energia para os seus m\u00fasculos. Se comer uma dieta <strong>vegetariana<\/strong> ou <strong>vegana <\/strong>, o gr\u00e3o-de-bico \u00e9 a escolha perfeita; eles asseguram que se obt\u00e9m prote\u00ednas suficientes sem produtos animais.<\/p>\n\n\n\n<p>Mas o gr\u00e3o de bico pode fazer ainda mais: para al\u00e9m do elevado teor de prote\u00ednas, cont\u00e9m muita <strong>fibra<\/strong> que o mant\u00e9m cheio durante muito tempo e baixa o n\u00edvel de a\u00e7\u00facar no sangue. Tem tamb\u00e9m <strong>vitamina<\/strong> C, \u00e1cido f\u00f3lico, vitamina E e vitaminas do complexo B. Tamb\u00e9m n\u00e3o cont\u00e9m gl\u00faten e cont\u00e9m minerais e oligoelementos tais como <strong>ferro<\/strong>, magn\u00e9sio, zinco, pot\u00e1ssio e c\u00e1lcio. Portanto, batatas fritas \u00e0 parte e vamos para o gr\u00e3o de bico! Embora&#8230; \u00e0s vezes se possa comer batatas fritas&#8230; Mas com gr\u00e3o-de-bico no menu, est\u00e1 bem equipado para fazer algo bom para os seus m\u00fasculos, nervos e ossos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-nutrientes-importantes-do-grao-de-bico\"><strong>Nutrientes<\/strong> importantes <strong>do<\/strong> gr\u00e3o de bico<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prote\u00edna<\/li>\n\n\n\n<li>Ferro de engomar<\/li>\n\n\n\n<li>Fibra diet\u00e9tica<\/li>\n\n\n\n<li>Vitaminas<\/li>\n\n\n\n<li>\u00c1cido f\u00f3lico<\/li>\n\n\n\n<li>Magn\u00e9sio<\/li>\n\n\n\n<li>Pot\u00e1ssio<\/li>\n\n\n\n<li>C\u00e1lcio<\/li>\n\n\n\n<li>Zinco<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-comprar-e-armazenar-grao-de-bico\">Comprar e armazenar gr\u00e3o de bico<\/h3>\n\n\n\n<p>Pode comprar gr\u00e3o-de-bico <strong>seco<\/strong> ou j\u00e1 <strong>cozinhado<\/strong> em latas e frascos. Pode encontr\u00e1-los em supermercados, lojas de alimentos saud\u00e1veis, mercados asi\u00e1ticos ou lojas de alimentos org\u00e2nicos. O gr\u00e3o-de-bico est\u00e1 dispon\u00edvel durante todo o <strong>ano<\/strong> porque as suas regi\u00f5es de cultivo t\u00eam sempre um clima quente, que necessitam para crescer. Armazenadas num local <strong>seco<\/strong> e <strong>fresco<\/strong>, as ervilhas podem ser guardadas indefinidamente. Se os tiver armazenado durante um per\u00edodo de tempo mais longo, basta verificar se existem pequenos buracos de vermes antes de comer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-preparacao-e-cozedura\">Prepara\u00e7\u00e3o e cozedura<\/h3>\n\n\n\n<p>O gr\u00e3o de bico cru cont\u00e9m a fase de <strong>toxina<\/strong>, mas esta decomp\u00f5e-se quando cozinhado. Por conseguinte, \u00e9 importante n\u00e3o comer as ervilhas <strong>cruas<\/strong>. Se os cozinharmos, o gr\u00e3o de bico \u00e9 <strong>seguro<\/strong> para comer.<\/p>\n\n\n\n<p>Pode comprar gr\u00e3o-de-bico <strong>seco<\/strong> ou j\u00e1 <strong>cozinhado<\/strong>. Se estiver com pressa, \u00e9 f\u00e1cil abrir a <strong>lata<\/strong> e come\u00e7ar. Basta deitar o gr\u00e3o de bico numa peneira e enxagu\u00e1-lo sob \u00e1gua corrente.<\/p>\n\n\n\n<p>Se tiver mais tempo para a prepara\u00e7\u00e3o, pode cozinhar o gr\u00e3o-de-bico <strong>voc\u00ea mesmo<\/strong>. Deve primeiro molh\u00e1-los antes de cozinhar. Isto torna os pulsos mais f\u00e1ceis de digerir e reduz consideravelmente o tempo de cozedura, preservando assim as muitas subst\u00e2ncias vitais durante a cozedura.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para <strong>mergulhar<\/strong>, cobrir o gr\u00e3o de bico com o dobro da quantidade de \u00e1gua numa tigela e deix\u00e1-los mergulhar durante a noite durante pelo menos 12 horas. Depois deitar fora a \u00e1gua de molho e lavar as ervilhas com \u00e1gua fresca.<\/li>\n\n\n\n<li>Depois est\u00e3o prontos para <strong>cozinhar<\/strong>. Cobrir o gr\u00e3o de bico com \u00e1gua fresca e deixar ferver. Deixar as ervilhas ferver suavemente em lume brando durante cerca de 60 minutos.<\/li>\n\n\n\n<li>O <strong>tempo de cozedura<\/strong> depende do que se quer fazer com o gr\u00e3o de bico. Para guisados, saladas, etc. 60 minutos \u00e9 suficiente, para hummus cremoso deve cozinh\u00e1-los um pouco mais, cerca de 90 minutos, para que fiquem agrad\u00e1veis e macios. As ervilhas s\u00e3o feitas quando se pode facilmente perfur\u00e1-las com uma faca, tal como as batatas.<\/li>\n\n\n\n<li>Se tiver uma <strong>panela de press\u00e3o<\/strong> em casa, as ervilhas embebidas demoram apenas cerca de 20 minutos a cozinhar.<\/li>\n\n\n\n<li>Se quiser <strong>assar<\/strong> o gr\u00e3o de bico no <strong>forno<\/strong>, deve ainda cozinh\u00e1-lo primeiro ou utilizar as ervilhas cozidas da lata. Depois aquecer o forno a 190 \u00b0C, misturar o gr\u00e3o de bico com um pouco de \u00f3leo (1 colher de sopa de \u00f3leo para 400 g de ervilhas) e coloc\u00e1-los num tabuleiro forrado com papel vegetal no forno durante 30-40 minutos. Depois tempere como quiser e petisque fora. Pode encontrar a minha <a href=\"https:\/\/bistrobadia.de\/pt\/fa\u00e7a-o-seu-pr\u00f3prio-gr\u00e3o-de-bico-assado\/\" target=\"_blank\" rel=\"noreferrer noopener\">receita<\/a> aqui.<\/li>\n<\/ul>\n\n\n\n<p>Depois de cozido, o gr\u00e3o de bico pode ser <strong>mantido no<\/strong> frigor\u00edfico durante cerca de quatro dias. E quanto \u00e0 <strong>pele<\/strong> fina do gr\u00e3o de bico que pode ser removida? Pode simplesmente comer a casca muito fina do gr\u00e3o de bico.<\/p>\n\n\n\n<p><strong>Dica interior<\/strong>: Se adicionar <strong>bicarbonato de s\u00f3dio<\/strong> \u00e0 \u00e1gua de cozedura, o <strong>tempo de cozedura \u00e9 reduzido<\/strong> para metade. Como o gr\u00e3o-de-bico demora muito tempo a cozinhar, este pequeno truque vai poupar-lhe muito tempo. O bicarbonato de s\u00f3dio \u00e9 uma base, se o adicionarmos \u00e0 \u00e1gua e o fervermos, \u00e9 desencadeada uma reac\u00e7\u00e3o qu\u00edmica que faz com que a pectina do gr\u00e3o de bico se dissolva mais rapidamente e as ervilhas absorvam \u00e1gua mais rapidamente, pelo que cozem mais rapidamente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-o-grao-de-bico-em-levantine-e-na-cozinha-mundial\">O gr\u00e3o de bico em Levantine e na cozinha mundial<\/h3>\n\n\n\n<p>O que a batata \u00e9 em alguns pa\u00edses, o gr\u00e3o de bico est\u00e1 no Levante. \u00c9 a base de muitas iguarias. Os dois pratos mais famosos a n\u00edvel mundial s\u00e3o da <strong>cozinha<\/strong> <strong>Levantine<\/strong> <strong>:<\/strong> <strong>falafel<\/strong> e <strong>hummus<\/strong>. Mas sabe o que s\u00e3o falafel, n\u00e3o sabe? Bem, falafel s\u00e3o bolas veganas fritas feitas de gr\u00e3o de bico, ervas arom\u00e1ticas e especiarias. A receita pode ser encontrada <a rel=\"noreferrer noopener\" href=\"https:\/\/bistrobadia.de\/pt\/fa\u00e7a-o-seu-pr\u00f3prio-falafel\/\" target=\"_blank\">aqui<\/a>. A prop\u00f3sito, hummus ou &#8220;hommus&#8221; significa &#8220;gr\u00e3o de bico&#8221; em \u00e1rabe.<\/p>\n\n\n\n<p>Em It\u00e1lia, a <strong>farinha de gr\u00e3o de bico<\/strong> \u00e9 utilizada para preparar &#8220;farinata&#8221;, na Gr\u00e9cia e no Levante as ervilhas s\u00e3o tamb\u00e9m mordiscadas como um <strong>lanche<\/strong>, assadas como nozes, e em Espanha, deliciosos e saborosos <strong>guisados<\/strong> s\u00e3o feitos com a leguminosa. Na \u00cdndia, o gr\u00e3o de bico \u00e9 o ingrediente principal da &#8220;chana masala&#8221;, um <strong>caril<\/strong> muito popular. \u00c9 tamb\u00e9m utilizado para <strong>pratos doces<\/strong> como o &#8220;laddu&#8221;.<\/p>\n\n\n\n<p>Como podem ver, o gr\u00e3o de bico \u00e9 realmente vers\u00e1til. Seja numa salada, sopa, guisado, creme, caril ou cozedura, nunca se aborrecer\u00e1 na cozinha com esta leguminosa.<\/p>\n\n\n\n<p><strong>Especiarias<\/strong> fortes como coentros ou cominhos s\u00e3o mais frequentemente utilizadas para a ervilha, mas n\u00e3o h\u00e1 limites para a sua imagina\u00e7\u00e3o. O gr\u00e3o de bico \u00e9 vers\u00e1til, basta experiment\u00e1-lo e ver o que mais lhe agrada.<\/p>\n\n\n\n<p>Usar o gr\u00e3o de bico:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>como<strong> ingrediente principal do<\/strong> seu prato e conjurar falafel, hummus ou farinata.<\/li>\n\n\n\n<li>Como<strong> substituto da carne <\/strong>, por exemplo, sob a forma de hamb\u00fargueres, que se formam a partir das ervilhas e das fritas.<\/li>\n\n\n\n<li>como<strong> ingrediente especial em <\/strong>saladas coloridas, guisados e ca\u00e7arolas<\/li>\n\n\n\n<li>para <strong>cozer<\/strong> e criar pratos doces a partir de farinha de gr\u00e3o de bico<\/li>\n\n\n\n<li>como um<strong> lanche <\/strong>, assando-os no forno com especiarias e \u00f3leo at\u00e9 ficarem dourados e estaladi\u00e7os.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aquafaba\">Aquafaba<\/h3>\n\n\n\n<p>Para al\u00e9m de prote\u00ednas, o gr\u00e3o de bico tem outro \u00e1s na manga como alternativa aos produtos animais: <strong>Aquafaba<\/strong>. Pode utilizar a <strong>\u00e1gua de gr\u00e3o de bico<\/strong> em lata como alternativa vegana para as claras de ovo batidas. Como \u00e9 que se faz? A \u00e1gua de gr\u00e3o de bico enlatado deve estar \u00e0 temperatura ambiente, depois pode ser batida com um processador de alimentos ou uma batedeira manual como as claras de ovo. Pode usar as claras de ovo batidas vegan para fazer mousse de chocolate, panquecas ou merengue.<\/p>\n\n\n\n<p>O gr\u00e3o de bico \u00e9 t\u00e3o vers\u00e1til que se pode invocar algo novo com ele todos os dias. Por isso agarra na tua colher de pau, agarra na tua ervilha e vamos l\u00e1 come\u00e7ar!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-aqui-estao-algumas-ideias-de-receitas-para-si\">Aqui est\u00e3o algumas ideias de receitas para si<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-saladas-deliciosas-com-grao-de-bico\">Saladas deliciosas com gr\u00e3o de bico:<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/pt\/salada-de-grao-de-bico-quente-balilah\/balilah-warmer-kichererbsensalat-3\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1024x683.jpg\" alt=\"Balilah warmer kichererbsensalat\" class=\"wp-image-6644 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1024x683.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1536x1025.jpg 1536w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1920x1281.jpg 1920w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-1170x780.jpg 1170w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-585x390.jpg 585w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat-263x175.jpg 263w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/06\/Balilah-warmer-kichererbsensalat.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"Balilah: Salada de gr\u00e3o de bico quente\">Balilah: Salada de gr\u00e3o de bico quente<\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/pt\/kichererbsensalat-mit-zaatar-dressing\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Kichererbsensalat-mit-Zaatar-Dressing-1024x683.jpg\" alt=\"Kichererbsensalat-mit-Zaatar-Dressing\" class=\"wp-image-5324 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Kichererbsensalat-mit-Zaatar-Dressing-1024x683.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Kichererbsensalat-mit-Zaatar-Dressing-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Kichererbsensalat-mit-Zaatar-Dressing-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Kichererbsensalat-mit-Zaatar-Dressing-1170x780.jpg 1170w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Kichererbsensalat-mit-Zaatar-Dressing-585x390.jpg 585w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Kichererbsensalat-mit-Zaatar-Dressing-263x175.jpg 263w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Kichererbsensalat-mit-Zaatar-Dressing.jpg 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/pt\/kichererbsensalat-mit-zaatar-dressing\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/bistrobadia.de\/pt\/salada-de-gr\u00e3o-de-bico-com-molho-de-zaatar\/\" target=\"_blank\" rel=\"noreferrer noopener\">Salada de gr\u00e3o de bico com za&#8217;atar<\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/rote-bete-salat-mit-kichererbsen-und-feta\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-1024x683.jpg\" alt=\"Rote Bete Salat mit Kichererbsen\" class=\"wp-image-5546 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-1024x683.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-1536x1024.jpg 1536w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-1920x1280.jpg 1920w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-1170x780.jpg 1170w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-585x390.jpg 585w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4-263x175.jpg 263w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/02\/Rote-Bete-Salat-mit-Kichererbsen-4.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/rote-bete-salat-mit-kichererbsen-und-feta\/\" target=\"_blank\" rel=\"noreferrer noopener\"><a href=\"https:\/\/bistrobadia.de\/pt\/salada-de-beterraba-com-gr\u00e3o-de-bico-e-queijo-feta\/\" target=\"_blank\" rel=\"noreferrer noopener\">Salada de beterraba com gr\u00e3o de bico<\/a><\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/pt\/nudelsalat-mit-kichererbsen-und-sumach-zwiebeln\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-1024x683.jpg\" alt=\"Nudelsalat mit Kichererbsen und Sumach-Zwiebeln\" class=\"wp-image-6185 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-1024x683.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-1536x1025.jpg 1536w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-1920x1281.jpg 1920w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-1170x780.jpg 1170w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-585x390.jpg 585w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln-263x175.jpg 263w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/04\/Nudelsalat-mit-Kichererbsen-und-Sumach-Zwiebeln.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/pt\/nudelsalat-mit-kichererbsen-und-sumach-zwiebeln\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/bistrobadia.de\/pt\/salada-de-massa-com-gr%C3%A3o-de-bico-e-cebola-sumagre\/\" target=\"_blank\" rel=\"noreferrer noopener\">Salada de massa com gr\u00e3o de bico e cebola sumagre<\/a><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-hummus-amp-co\">Hummus &amp; Co.<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/pt\/hummus\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-Kichererbsencreme-1024x683.jpg\" alt=\"Hummus\" class=\"wp-image-3430 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-Kichererbsencreme.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-Kichererbsencreme-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-Kichererbsencreme-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-Kichererbsencreme-500x333.jpg 500w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-Kichererbsencreme-100x67.jpg 100w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-Kichererbsencreme-1016x678.jpg 1016w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/pt\/hummus\/\" target=\"_blank\" rel=\"noreferrer noopener\"><a href=\"https:\/\/bistrobadia.de\/pt\/hummus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hummus<\/a><\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/hummus-tartar\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-mit-Hack-1024x682.jpg\" alt=\"Hummus mit Hack\" class=\"wp-image-142 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-mit-Hack-1024x682.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-mit-Hack-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-mit-Hack-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-mit-Hack-500x333.jpg 500w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-mit-Hack-100x67.jpg 100w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/Hummus-mit-Hack.jpg 1037w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/682;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/hummus-tartar\/\" target=\"_blank\" rel=\"noreferrer noopener\"><a href=\"https:\/\/bistrobadia.de\/pt\/hummus-tartar\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hummus com carne picada<\/a><\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/rote-bete-hummus\/\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/05\/Rote-Bete-Hummus-1024x683.jpg\" alt=\"Rote Bete Hummus Kichererbse Creme\" class=\"wp-image-3435 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/05\/Rote-Bete-Hummus.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/05\/Rote-Bete-Hummus-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/05\/Rote-Bete-Hummus-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/05\/Rote-Bete-Hummus-500x333.jpg 500w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/05\/Rote-Bete-Hummus-100x67.jpg 100w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/05\/Rote-Bete-Hummus-1016x678.jpg 1016w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/rote-bete-hummus\/\" target=\"_blank\" rel=\"noreferrer noopener\"><a href=\"https:\/\/bistrobadia.de\/pt\/hummus-de-beterraba\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hummus de beterraba<\/a><\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/suesskartoffel-hummus\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/07\/S\u00fc\u00dfkartoffel-Hummus-Dip-Creme-1024x683.jpg\" alt=\"S\u00fc\u00dfkartoffel Hummus Dip Creme\" class=\"wp-image-3647 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/07\/S\u00fc\u00dfkartoffel-Hummus-Dip-Creme.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/07\/S\u00fc\u00dfkartoffel-Hummus-Dip-Creme-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/07\/S\u00fc\u00dfkartoffel-Hummus-Dip-Creme-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/07\/S\u00fc\u00dfkartoffel-Hummus-Dip-Creme-500x333.jpg 500w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/07\/S\u00fc\u00dfkartoffel-Hummus-Dip-Creme-100x67.jpg 100w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2019\/07\/S\u00fc\u00dfkartoffel-Hummus-Dip-Creme-1016x678.jpg 1016w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/pt\/hummus-de-batata-doce\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hummus de Batata Doce<\/a><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-os-classicos\">Os cl\u00e1ssicos<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/bistrobadia.de\/falafel-selber-machen\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/08\/Falafel_.jpg\" alt=\"Falafel\" class=\"wp-image-4284 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/08\/Falafel_.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/08\/Falafel_-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/08\/Falafel_-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/08\/Falafel_-500x333.jpg 500w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/08\/Falafel_-100x67.jpg 100w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/08\/Falafel_-1016x678.jpg 1016w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/pt\/fa\u00e7a-o-seu-pr\u00f3prio-falafel\/\" target=\"_blank\" rel=\"noreferrer noopener\">Falafel<\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2017\/01\/Aubergine-Kichererbse2-web-1024x683.jpg\" alt=\"Aubergine\" class=\"wp-image-1306 lazyload\" data-srcset=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2017\/01\/Aubergine-Kichererbse2-web.jpg 1024w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2017\/01\/Aubergine-Kichererbse2-web-300x200.jpg 300w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2017\/01\/Aubergine-Kichererbse2-web-768x512.jpg 768w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2017\/01\/Aubergine-Kichererbse2-web-500x333.jpg 500w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2017\/01\/Aubergine-Kichererbse2-web-100x67.jpg 100w, https:\/\/bistrobadia.de\/wp-content\/uploads\/2017\/01\/Aubergine-Kichererbse2-web-1016x678.jpg 1016w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/bistrobadia.de\/musakaa\/\" target=\"_blank\" rel=\"noreferrer noopener\"><a href=\"https:\/\/bistrobadia.de\/pt\/musakaa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Musaka&#8217;a<\/a><\/a><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Imagine se n\u00e3o houvesse gr\u00e3o de bico&#8230; Ent\u00e3o n\u00e3o havia&#8230;<\/p>\n","protected":false},"author":1,"featured_media":16522,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[4627],"tags":[],"class_list":["post-16520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>O grande guia do gr\u00e3o de bico: tudo o que precisa de saber!<\/title>\n<meta name=\"description\" content=\"O gr\u00e3o-de-bico n\u00e3o s\u00f3 \u00e9 delicioso, como tamb\u00e9m muito nutritivo e saud\u00e1vel. Descubra tudo o que precisa de saber sobre o gr\u00e3o de bico no guia do gr\u00e3o de bico grande.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber sobre a ervilha pequena\" \/>\n<meta property=\"og:description\" content=\"O gr\u00e3o-de-bico n\u00e3o s\u00f3 \u00e9 delicioso, como tamb\u00e9m muito nutritivo e saud\u00e1vel. Descubra tudo o que precisa de saber sobre o gr\u00e3o de bico no guia do gr\u00e3o de bico grande.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/\" \/>\n<meta property=\"og:site_name\" content=\"Bistro Badia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bistrobadia\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-27T12:30:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-25T11:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-Feld-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafik Halabi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafik Halabi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/\"},\"author\":{\"name\":\"Rafik Halabi\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#\\\/schema\\\/person\\\/fa7e5cf95714a3582b7a4e1bc990e0ad\"},\"headline\":\"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber sobre a ervilha pequena\",\"datePublished\":\"2020-05-27T12:30:56+00:00\",\"dateModified\":\"2024-01-25T11:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/\"},\"wordCount\":1694,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Kichererbsen-Feld-scaled.jpg\",\"articleSection\":[\"Revista\"],\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/\",\"name\":\"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Kichererbsen-Feld-scaled.jpg\",\"datePublished\":\"2020-05-27T12:30:56+00:00\",\"dateModified\":\"2024-01-25T11:54:53+00:00\",\"description\":\"O gr\u00e3o-de-bico n\u00e3o s\u00f3 \u00e9 delicioso, como tamb\u00e9m muito nutritivo e saud\u00e1vel. Descubra tudo o que precisa de saber sobre o gr\u00e3o de bico no guia do gr\u00e3o de bico grande.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/#breadcrumb\"},\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Kichererbsen-Feld-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Kichererbsen-Feld-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/guia-do-gr%c3%a3o-de-bico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revista\",\"item\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/categoria\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber sobre a ervilha pequena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/\",\"name\":\"Bistro Badia\",\"description\":\"Rezepte aus dem Libanon und der Levante\",\"publisher\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#organization\",\"name\":\"Bistro Badia\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/kleines-logo-gr\u00fcn.jpg\",\"contentUrl\":\"https:\\\/\\\/bistrobadia.de\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/kleines-logo-gr\u00fcn.jpg\",\"width\":2048,\"height\":1448,\"caption\":\"Bistro Badia\"},\"image\":{\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bistrobadia\",\"https:\\\/\\\/www.instagram.com\\\/bistrobadia.de\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/bistrobadia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/#\\\/schema\\\/person\\\/fa7e5cf95714a3582b7a4e1bc990e0ad\",\"name\":\"Rafik Halabi\",\"description\":\"Hey! Willkommen auf Bistro Badia! Ich bin Rafik und ich freue mich sehr, dass Du hier bist.\",\"url\":\"https:\\\/\\\/bistrobadia.de\\\/pt\\\/author\\\/rafik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber!","description":"O gr\u00e3o-de-bico n\u00e3o s\u00f3 \u00e9 delicioso, como tamb\u00e9m muito nutritivo e saud\u00e1vel. Descubra tudo o que precisa de saber sobre o gr\u00e3o de bico no guia do gr\u00e3o de bico grande.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/","og_locale":"pt_PT","og_type":"article","og_title":"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber sobre a ervilha pequena","og_description":"O gr\u00e3o-de-bico n\u00e3o s\u00f3 \u00e9 delicioso, como tamb\u00e9m muito nutritivo e saud\u00e1vel. Descubra tudo o que precisa de saber sobre o gr\u00e3o de bico no guia do gr\u00e3o de bico grande.","og_url":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/","og_site_name":"Bistro Badia","article_publisher":"https:\/\/www.facebook.com\/bistrobadia","article_published_time":"2020-05-27T12:30:56+00:00","article_modified_time":"2024-01-25T11:54:53+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-Feld-scaled.jpg","type":"image\/jpeg"}],"author":"Rafik Halabi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rafik Halabi","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/#article","isPartOf":{"@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/"},"author":{"name":"Rafik Halabi","@id":"https:\/\/bistrobadia.de\/pt\/#\/schema\/person\/fa7e5cf95714a3582b7a4e1bc990e0ad"},"headline":"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber sobre a ervilha pequena","datePublished":"2020-05-27T12:30:56+00:00","dateModified":"2024-01-25T11:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/"},"wordCount":1694,"commentCount":0,"publisher":{"@id":"https:\/\/bistrobadia.de\/pt\/#organization"},"image":{"@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/#primaryimage"},"thumbnailUrl":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-Feld-scaled.jpg","articleSection":["Revista"],"inLanguage":"pt","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/","url":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/","name":"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber!","isPartOf":{"@id":"https:\/\/bistrobadia.de\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/#primaryimage"},"image":{"@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/#primaryimage"},"thumbnailUrl":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-Feld-scaled.jpg","datePublished":"2020-05-27T12:30:56+00:00","dateModified":"2024-01-25T11:54:53+00:00","description":"O gr\u00e3o-de-bico n\u00e3o s\u00f3 \u00e9 delicioso, como tamb\u00e9m muito nutritivo e saud\u00e1vel. Descubra tudo o que precisa de saber sobre o gr\u00e3o de bico no guia do gr\u00e3o de bico grande.","breadcrumb":{"@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/#breadcrumb"},"inLanguage":"pt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/"]}]},{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/#primaryimage","url":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-Feld-scaled.jpg","contentUrl":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-Feld-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/bistrobadia.de\/pt\/guia-do-gr%c3%a3o-de-bico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/bistrobadia.de\/pt\/"},{"@type":"ListItem","position":2,"name":"Revista","item":"https:\/\/bistrobadia.de\/pt\/categoria\/revista\/"},{"@type":"ListItem","position":3,"name":"O grande guia do gr\u00e3o de bico: tudo o que precisa de saber sobre a ervilha pequena"}]},{"@type":"WebSite","@id":"https:\/\/bistrobadia.de\/pt\/#website","url":"https:\/\/bistrobadia.de\/pt\/","name":"Bistro Badia","description":"Rezepte aus dem Libanon und der Levante","publisher":{"@id":"https:\/\/bistrobadia.de\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bistrobadia.de\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt"},{"@type":"Organization","@id":"https:\/\/bistrobadia.de\/pt\/#organization","name":"Bistro Badia","url":"https:\/\/bistrobadia.de\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/bistrobadia.de\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/kleines-logo-gr\u00fcn.jpg","contentUrl":"https:\/\/bistrobadia.de\/wp-content\/uploads\/2016\/06\/kleines-logo-gr\u00fcn.jpg","width":2048,"height":1448,"caption":"Bistro Badia"},"image":{"@id":"https:\/\/bistrobadia.de\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bistrobadia","https:\/\/www.instagram.com\/bistrobadia.de\/","https:\/\/www.pinterest.de\/bistrobadia\/"]},{"@type":"Person","@id":"https:\/\/bistrobadia.de\/pt\/#\/schema\/person\/fa7e5cf95714a3582b7a4e1bc990e0ad","name":"Rafik Halabi","description":"Hey! Willkommen auf Bistro Badia! Ich bin Rafik und ich freue mich sehr, dass Du hier bist.","url":"https:\/\/bistrobadia.de\/pt\/author\/rafik\/"}]}},"taxonomy_info":{"category":[{"value":4627,"label":"Revista"}]},"featured_image_src_large":["https:\/\/bistrobadia.de\/wp-content\/uploads\/2020\/05\/Kichererbsen-Feld-1024x576.jpg",1024,576,true],"author_info":{"display_name":"Rafik Halabi","author_link":"https:\/\/bistrobadia.de\/pt\/author\/rafik\/"},"comment_info":0,"category_info":[{"term_id":4627,"name":"Revista","slug":"revista","term_group":0,"term_taxonomy_id":4627,"taxonomy":"category","description":"Na revista encontrar\u00e1 grandes artigos sobre a cozinha do Levant. Pouco a pouco, vai-se enchendo de guias, dicas e truques. E se estiver interessado em algo que ainda n\u00e3o tenha sido publicado aqui, basta deixar-me uma linha.","parent":0,"count":20,"filter":"raw","term_order":"11","cat_ID":4627,"category_count":20,"category_description":"Na revista encontrar\u00e1 grandes artigos sobre a cozinha do Levant. Pouco a pouco, vai-se enchendo de guias, dicas e truques. E se estiver interessado em algo que ainda n\u00e3o tenha sido publicado aqui, basta deixar-me uma linha.","cat_name":"Revista","category_nicename":"revista","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/posts\/16520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/comments?post=16520"}],"version-history":[{"count":0,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/posts\/16520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/media\/16522"}],"wp:attachment":[{"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/media?parent=16520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/categories?post=16520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bistrobadia.de\/pt\/wp-json\/wp\/v2\/tags?post=16520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}